{"id":39978,"date":"2026-02-13T13:18:00","date_gmt":"2026-02-13T12:18:00","guid":{"rendered":"https:\/\/investx.fr\/de\/?p=39978"},"modified":"2026-02-13T11:38:28","modified_gmt":"2026-02-13T10:38:28","slug":"coinbase-absturz-ceo-verkauf-pleite","status":"publish","type":"post","link":"https:\/\/investx.fr\/de\/krypto-news\/coinbase-absturz-ceo-verkauf-pleite\/","title":{"rendered":"Coinbase-Absturz &#038; CEO-Verkauf: Steht der B\u00f6rsenriese vor dem Aus?"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\" class=\"wp-block-heading\" id=\"enttaeuschende-q4-ergebnisse-und-massive-ceo-verkaeufe\">Entt\u00e4uschende Q4-Ergebnisse und massive CEO-Verk\u00e4ufe<\/h2>\n\n\n\n<p>Die Reaktion auf die <a href=\"https:\/\/investx.fr\/de\/investieren-krypto\/exchange-ranking\/\">Exchange<\/a> aus den USA war unmittelbar. Der Bericht f\u00fcr das vierte Quartal 2025 zeigt Leistungen, die deutlich unter dem Konsens liegen. <a href=\"https:\/\/investx.fr\/de\/investieren-krypto\/exchange\/coinbase\/vip-programm\/\">Coinbase<\/a> wies einen Gewinn je Aktie (EPS) von nur <strong>0,66 $<\/strong> aus, weit entfernt von den von Analysten erwarteten 1,05 $. Auch der Umsatz blieb zur\u00fcck und belief sich auf <strong>1,78 Milliarden Dollar<\/strong> gegen\u00fcber einer Prognose von 1,85 Milliarden. Noch besorgniserregender ist, dass das Unternehmen einen Nettoverlust von 667 Millionen Dollar verzeichnete, belastet durch Abschreibungen auf sein <a href=\"https:\/\/investx.fr\/de\/investieren-krypto\/kaufen\/\">Krypto<\/a>-Portfolio.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">There is absolutely no reason to keep your funds on coinbase.<br><br>At any moment they can be gone forever.<br><br>And with the CEO dumping $550m of stock onto your head it\u2019s clear everyone wants an exit. <a href=\"https:\/\/t.co\/zgFXr5RQGR\">pic.twitter.com\/zgFXr5RQGR<\/a><\/p>&mdash; Crypto Bitlord (@crypto_bitlord7) <a href=\"https:\/\/twitter.com\/crypto_bitlord7\/status\/2022020472809087029?ref_src=twsrc%5Etfw\">February 12, 2026<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<p>\u00dcber die Bilanzzahlen hinaus wird die Marktstimmung stark durch interne Bewegungen beeinflusst. Brian Armstrong, der CEO von Coinbase, verst\u00e4rkte den Verkaufsdruck, indem er zwischen April 2025 und Januar 2026 Aktien im Wert von mehr als <strong>550 Millionen Dollar<\/strong> liquidierte. Dieses Signal, das oft als mangelndes kurzfristiges Vertrauen von Insidern interpretiert wird, k\u00fchlte die Begeisterung institutioneller Investoren ab und veranlasste Banken wie JPMorgan dazu, ihre Kursziele nach unten zu revidieren.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" class=\"wp-block-heading\" id=\"technische-analyse-die-kritische-unterstuetzung-steht-unter-druck\">Technische Analyse: Die kritische Unterst\u00fctzung steht unter Druck<\/h2>\n\n\n\n<p>Aus technischer Sicht ist die Struktur von COIN kurzfristig eindeutig <strong>bearish<\/strong>. Der heftige Bruch des Niveaus von 153 $ (ehemalige Unterst\u00fctzung, die zum Widerstand wurde) trieb den Kurs in Richtung der Zone von 141 $. Die Momentum-Indikatoren wie der RSI fallen in den \u00fcberverkauften Bereich, was auf intensiven Verkaufsdruck hindeutet, aber die M\u00f6glichkeit einer technischen Reflexerholung andeutet.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"751\" src=\"https:\/\/investx.fr\/de\/wp-content\/uploads\/sites\/3\/2026\/02\/COIN_2026-02-13_09-51-07-1024x751-1.jpg\" alt=\"Coinbase Aktienkurs Analyse mit RSI und Orderblock\" class=\"wp-image-39976\" srcset=\"https:\/\/media.investx.fr\/wp-content\/uploads\/sites\/3\/2026\/02\/COIN_2026-02-13_09-51-07-1024x751-1.jpg 1024w, https:\/\/media.investx.fr\/wp-content\/uploads\/sites\/3\/2026\/02\/COIN_2026-02-13_09-51-07-1024x751-1-300x220.jpg 300w, https:\/\/media.investx.fr\/wp-content\/uploads\/sites\/3\/2026\/02\/COIN_2026-02-13_09-51-07-1024x751-1-768x563.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Sollte dieses Niveau von 140 $ unter Volumen nachgeben, k\u00f6nnte sich der Fall in Richtung der psychologischen Zone von 90 $ beschleunigen. Umgekehrt m\u00fcssen die Bulls, um eine Trendwende zu erreichen, unbedingt die <strong>153 $<\/strong> zur\u00fcckerobern und dann den Widerstand von 162 $ angreifen, um eine nachhaltige bullische Umkehr zu best\u00e4tigen.<\/p>\n\n\n\n<p>Die aktuelle Konfiguration mahnt zu \u00e4u\u00dferster Vorsicht. Mit diesen Ausf\u00e4llen der Exchange und den massiven CEO-Verk\u00e4ufen k\u00f6nnte der Crash heftiger ausfallen. Andererseits kann diese Art von FUD das Smart Money anziehen, das die Panik kauft. In jedem Fall muss man <strong>geduldig bleiben<\/strong>, solange die <strong>153 $<\/strong> und die Trendlinie nicht zur\u00fcckgewonnen werden.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/t.me\/+z-a5LKRM7HxkNWZk\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Greife auf Profi-Trades zu: Tritt der privaten Gruppe bei (kostenloser Zugang, nur f\u00fcr erfahrene Trader).<\/a><\/div>\n<\/div>\n\n\n\n<p><strong>Verwandte Artikel:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/investx.fr\/de\/krypto-news\/dogecoin-meme-coins-2026\/\">Kann Dogecoin den Meme-Coin-Superzyklus 2026 wiederbeleben?<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/investx.fr\/de\/krypto-news\/xrp-etf-bullrun-analyse\/\">XRP ETFs explodieren: Start eines neuen Bull Runs?<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/investx.fr\/de\/krypto-news\/elon-musk-x-money-krypto\/\">Elon Musk k\u00fcndigt X Money in 2 Monaten an: Kann es den Kryptomarkt explodieren lassen?<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Coinbase-Aktie im Sinkflug! Was bedeuten die schlechten Quartalszahlen und der Verkauf von Anteilen durch den CEO? Jetzt lesen!<\/p>\n","protected":false},"author":32,"featured_media":39977,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","faq_titre":"","questions_frequentes":"","custom_permalink":"krypto-news\/coinbase-absturz-ceo-verkauf-pleite"},"categories":[16,11],"tags":[],"class_list":["post-39978","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-exchanges","category-krypto-news"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Coinbase in der Krise? Absturz, CEO-Verkauf &amp; drohende Pleite?<\/title>\n<meta name=\"description\" content=\"Coinbase-Aktie im Sinkflug! Was bedeuten die schlechten Quartalszahlen und der Verkauf von Anteilen durch den CEO? Jetzt lesen!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/investx.fr\/de\/krypto-news\/coinbase-absturz-ceo-verkauf-pleite\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Coinbase in der Krise? Absturz, CEO-Verkauf &amp; drohende Pleite?\" \/>\n<meta property=\"og:description\" content=\"Coinbase-Aktie im Sinkflug! Was bedeuten die schlechten Quartalszahlen und der Verkauf von Anteilen durch den CEO? Jetzt lesen!\" \/>\n<meta property=\"og:site_name\" content=\"InvestX \u2013 Krypto-News, Trading-Guide, Preisanalysen &amp; Prognosen\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-13T12:18:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/investx.fr\/de\/wp-content\/uploads\/sites\/3\/2026\/02\/Laction-des-prix-de-Cardano-et-les-niveaux-a-venir-13-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"840\" \/>\n\t<meta property=\"og:image:height\" content=\"560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Charles Ledoux\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@charl3li\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Charles Ledoux\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/investx.fr\\\/de\\\/krypto-news\\\/coinbase-absturz-ceo-verkauf-pleite\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/investx.fr\\\/de\\\/krypto-news\\\/coinbase-absturz-ceo-verkauf-pleite\\\/\"},\"author\":{\"name\":\"Charles Ledoux\",\"@id\":\"https:\\\/\\\/investx.fr\\\/de\\\/#\\\/schema\\\/person\\\/a99817b9d097ee5a69e24946de94c23a\"},\"headline\":\"Coinbase-Absturz &#038; CEO-Verkauf: Steht der B\u00f6rsenriese vor dem Aus?\",\"datePublished\":\"2026-02-13T12:18:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/investx.fr\\\/de\\\/krypto-news\\\/coinbase-absturz-ceo-verkauf-pleite\\\/\"},\"wordCount\":381,\"publisher\":{\"@id\":\"https:\\\/\\\/investx.fr\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/investx.fr\\\/de\\\/krypto-news\\\/coinbase-absturz-ceo-verkauf-pleite\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.investx.fr\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2026\\\/02\\\/Laction-des-prix-de-Cardano-et-les-niveaux-a-venir-13-1.jpg?wsr\",\"articleSection\":[\"Exchanges\",\"News\"],\"inLanguage\":\"de\",\"copyrightYear\":\"2026\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/investx.fr\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/investx.fr\\\/de\\\/krypto-news\\\/coinbase-absturz-ceo-verkauf-pleite\\\/\",\"url\":\"https:\\\/\\\/investx.fr\\\/de\\\/krypto-news\\\/coinbase-absturz-ceo-verkauf-pleite\\\/\",\"name\":\"Coinbase in der Krise? Absturz, CEO-Verkauf & drohende Pleite?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/investx.fr\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/investx.fr\\\/de\\\/krypto-news\\\/coinbase-absturz-ceo-verkauf-pleite\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/investx.fr\\\/de\\\/krypto-news\\\/coinbase-absturz-ceo-verkauf-pleite\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.investx.fr\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2026\\\/02\\\/Laction-des-prix-de-Cardano-et-les-niveaux-a-venir-13-1.jpg?wsr\",\"datePublished\":\"2026-02-13T12:18:00+00:00\",\"description\":\"Coinbase-Aktie im Sinkflug! Was bedeuten die schlechten Quartalszahlen und der Verkauf von Anteilen durch den CEO? Jetzt lesen!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/investx.fr\\\/de\\\/krypto-news\\\/coinbase-absturz-ceo-verkauf-pleite\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/investx.fr\\\/de\\\/krypto-news\\\/coinbase-absturz-ceo-verkauf-pleite\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/investx.fr\\\/de\\\/krypto-news\\\/coinbase-absturz-ceo-verkauf-pleite\\\/#primaryimage\",\"url\":\"https:\\\/\\\/media.investx.fr\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2026\\\/02\\\/Laction-des-prix-de-Cardano-et-les-niveaux-a-venir-13-1.jpg?wsr\",\"contentUrl\":\"https:\\\/\\\/media.investx.fr\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2026\\\/02\\\/Laction-des-prix-de-Cardano-et-les-niveaux-a-venir-13-1.jpg?wsr\",\"width\":840,\"height\":560,\"caption\":\"Coin COIN de Coinbase sur un fond orange avec une fleche trendline\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/investx.fr\\\/de\\\/krypto-news\\\/coinbase-absturz-ceo-verkauf-pleite\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/investx.fr\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Coinbase-Absturz &#038; CEO-Verkauf: Steht der B\u00f6rsenriese vor dem Aus?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/investx.fr\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/investx.fr\\\/de\\\/\",\"name\":\"InvestX \u2013 Krypto-News, Trading-Guide, Preisanalysen & Prognosen\",\"description\":\"T\u00e4gliche Krypto-News und unbegrenzte Ressourcen zu Kryptow\u00e4hrungen, Trading, Blockchain, DeFi und mehr.\",\"publisher\":{\"@id\":\"https:\\\/\\\/investx.fr\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/investx.fr\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/investx.fr\\\/de\\\/#organization\",\"name\":\"InvestX \u2013 Krypto-News, Trading-Guide, Preisanalysen & Prognosen\",\"url\":\"https:\\\/\\\/investx.fr\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/investx.fr\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/investx.fr\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/02\\\/investx_logo_tr.png\",\"contentUrl\":\"https:\\\/\\\/investx.fr\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/02\\\/investx_logo_tr.png\",\"width\":1366,\"height\":768,\"caption\":\"InvestX \u2013 Krypto-News, Trading-Guide, Preisanalysen & Prognosen\"},\"image\":{\"@id\":\"https:\\\/\\\/investx.fr\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/investx.fr\\\/de\\\/#\\\/schema\\\/person\\\/a99817b9d097ee5a69e24946de94c23a\",\"name\":\"Charles Ledoux\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/47d3a48e5bca34238d22886640ecc684e7dd54ad63c435f7005f6b5a1e0ddf8c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/47d3a48e5bca34238d22886640ecc684e7dd54ad63c435f7005f6b5a1e0ddf8c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/47d3a48e5bca34238d22886640ecc684e7dd54ad63c435f7005f6b5a1e0ddf8c?s=96&d=mm&r=g\",\"caption\":\"Charles Ledoux\"},\"description\":\"Je suis un analyste sp\u00e9cialis\u00e9 dans les blockchains L1 et leurs fondamentaux comme Bitcoin, Kaspa, Monero, Chainlink ou encore Solana. Je suis \u00e9galement form\u00e9 au trading et \u00e0 l\u2019analyse technique depuis plus d\u2019un an sur le march\u00e9 des cryptomonnaies, mais \u00e9galement sur le forex et les m\u00e9taux pr\u00e9cieux comme l\u2019or ou le silver. J\u2019ai obtenu un dipl\u00f4me de la Crypto Academy sur les fondamentaux techniques du Bitcoin et poss\u00e8de une exp\u00e9rience de plus de 5 ans dans le journalisme et l\u2019\u00e9criture d\u2019articles p\u00e9dagogiques. J\u2019ai notamment \u00e9crit de nombreuses masterclass pour \u00e9duquer les nouveaux venus dans l'industrie et plus de 10 000 articles et news.J\u2019ai \u00e9galement pu interviewer de nombreux fondateurs et cr\u00e9ateurs de projets dans la crypto comme Marc Lebreton (chef marketing de la blockchain SUI), EJ Ayala (Coinbase US et Draftkings), et d\u2019autres projets comme Polyhedra (Eric Vreeland), Usual (Adli Takkal Bataille), ou encore Humanity Protocol (Jade Gu). J\u2019ai plong\u00e9 dans la cryptomonnaie il y a plus de 3 ans et continue de mettre tout en \u0153uvre pour fournir du contenu de qualit\u00e9, avec de l\u2019expertise et la neutralit\u00e9 attendue d\u2019un journaliste. Retrouvez moi aussi sur X pour des analyses et sur Linkedin pour me contacter.\",\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/in\\\/charles-ledoux-508392239\\\/\",\"https:\\\/\\\/x.com\\\/charl3li\"],\"url\":\"https:\\\/\\\/investx.fr\\\/de\\\/author\\\/charles-ledoux\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Coinbase in der Krise? Absturz, CEO-Verkauf & drohende Pleite?","description":"Coinbase-Aktie im Sinkflug! Was bedeuten die schlechten Quartalszahlen und der Verkauf von Anteilen durch den CEO? Jetzt lesen!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/investx.fr\/de\/krypto-news\/coinbase-absturz-ceo-verkauf-pleite\/","og_locale":"de_DE","og_type":"article","og_title":"Coinbase in der Krise? Absturz, CEO-Verkauf & drohende Pleite?","og_description":"Coinbase-Aktie im Sinkflug! Was bedeuten die schlechten Quartalszahlen und der Verkauf von Anteilen durch den CEO? Jetzt lesen!","og_site_name":"InvestX \u2013 Krypto-News, Trading-Guide, Preisanalysen &amp; Prognosen","article_published_time":"2026-02-13T12:18:00+00:00","og_image":[{"width":840,"height":560,"url":"https:\/\/investx.fr\/de\/wp-content\/uploads\/sites\/3\/2026\/02\/Laction-des-prix-de-Cardano-et-les-niveaux-a-venir-13-1.jpg","type":"image\/jpeg"}],"author":"Charles Ledoux","twitter_card":"summary_large_image","twitter_creator":"@charl3li","twitter_misc":{"Verfasst von":"Charles Ledoux","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/investx.fr\/de\/krypto-news\/coinbase-absturz-ceo-verkauf-pleite\/#article","isPartOf":{"@id":"https:\/\/investx.fr\/de\/krypto-news\/coinbase-absturz-ceo-verkauf-pleite\/"},"author":{"name":"Charles Ledoux","@id":"https:\/\/investx.fr\/de\/#\/schema\/person\/a99817b9d097ee5a69e24946de94c23a"},"headline":"Coinbase-Absturz &#038; CEO-Verkauf: Steht der B\u00f6rsenriese vor dem Aus?","datePublished":"2026-02-13T12:18:00+00:00","mainEntityOfPage":{"@id":"https:\/\/investx.fr\/de\/krypto-news\/coinbase-absturz-ceo-verkauf-pleite\/"},"wordCount":381,"publisher":{"@id":"https:\/\/investx.fr\/de\/#organization"},"image":{"@id":"https:\/\/investx.fr\/de\/krypto-news\/coinbase-absturz-ceo-verkauf-pleite\/#primaryimage"},"thumbnailUrl":"https:\/\/media.investx.fr\/wp-content\/uploads\/sites\/3\/2026\/02\/Laction-des-prix-de-Cardano-et-les-niveaux-a-venir-13-1.jpg?wsr","articleSection":["Exchanges","News"],"inLanguage":"de","copyrightYear":"2026","copyrightHolder":{"@id":"https:\/\/investx.fr\/#organization"}},{"@type":"WebPage","@id":"https:\/\/investx.fr\/de\/krypto-news\/coinbase-absturz-ceo-verkauf-pleite\/","url":"https:\/\/investx.fr\/de\/krypto-news\/coinbase-absturz-ceo-verkauf-pleite\/","name":"Coinbase in der Krise? Absturz, CEO-Verkauf & drohende Pleite?","isPartOf":{"@id":"https:\/\/investx.fr\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/investx.fr\/de\/krypto-news\/coinbase-absturz-ceo-verkauf-pleite\/#primaryimage"},"image":{"@id":"https:\/\/investx.fr\/de\/krypto-news\/coinbase-absturz-ceo-verkauf-pleite\/#primaryimage"},"thumbnailUrl":"https:\/\/media.investx.fr\/wp-content\/uploads\/sites\/3\/2026\/02\/Laction-des-prix-de-Cardano-et-les-niveaux-a-venir-13-1.jpg?wsr","datePublished":"2026-02-13T12:18:00+00:00","description":"Coinbase-Aktie im Sinkflug! Was bedeuten die schlechten Quartalszahlen und der Verkauf von Anteilen durch den CEO? Jetzt lesen!","breadcrumb":{"@id":"https:\/\/investx.fr\/de\/krypto-news\/coinbase-absturz-ceo-verkauf-pleite\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/investx.fr\/de\/krypto-news\/coinbase-absturz-ceo-verkauf-pleite\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/investx.fr\/de\/krypto-news\/coinbase-absturz-ceo-verkauf-pleite\/#primaryimage","url":"https:\/\/media.investx.fr\/wp-content\/uploads\/sites\/3\/2026\/02\/Laction-des-prix-de-Cardano-et-les-niveaux-a-venir-13-1.jpg?wsr","contentUrl":"https:\/\/media.investx.fr\/wp-content\/uploads\/sites\/3\/2026\/02\/Laction-des-prix-de-Cardano-et-les-niveaux-a-venir-13-1.jpg?wsr","width":840,"height":560,"caption":"Coin COIN de Coinbase sur un fond orange avec une fleche trendline"},{"@type":"BreadcrumbList","@id":"https:\/\/investx.fr\/de\/krypto-news\/coinbase-absturz-ceo-verkauf-pleite\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/investx.fr\/de\/"},{"@type":"ListItem","position":2,"name":"Coinbase-Absturz &#038; CEO-Verkauf: Steht der B\u00f6rsenriese vor dem Aus?"}]},{"@type":"WebSite","@id":"https:\/\/investx.fr\/de\/#website","url":"https:\/\/investx.fr\/de\/","name":"InvestX \u2013 Krypto-News, Trading-Guide, Preisanalysen & Prognosen","description":"T\u00e4gliche Krypto-News und unbegrenzte Ressourcen zu Kryptow\u00e4hrungen, Trading, Blockchain, DeFi und mehr.","publisher":{"@id":"https:\/\/investx.fr\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/investx.fr\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/investx.fr\/de\/#organization","name":"InvestX \u2013 Krypto-News, Trading-Guide, Preisanalysen & Prognosen","url":"https:\/\/investx.fr\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/investx.fr\/de\/#\/schema\/logo\/image\/","url":"https:\/\/investx.fr\/de\/wp-content\/uploads\/sites\/3\/2025\/02\/investx_logo_tr.png","contentUrl":"https:\/\/investx.fr\/de\/wp-content\/uploads\/sites\/3\/2025\/02\/investx_logo_tr.png","width":1366,"height":768,"caption":"InvestX \u2013 Krypto-News, Trading-Guide, Preisanalysen & Prognosen"},"image":{"@id":"https:\/\/investx.fr\/de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/investx.fr\/de\/#\/schema\/person\/a99817b9d097ee5a69e24946de94c23a","name":"Charles Ledoux","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/47d3a48e5bca34238d22886640ecc684e7dd54ad63c435f7005f6b5a1e0ddf8c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/47d3a48e5bca34238d22886640ecc684e7dd54ad63c435f7005f6b5a1e0ddf8c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/47d3a48e5bca34238d22886640ecc684e7dd54ad63c435f7005f6b5a1e0ddf8c?s=96&d=mm&r=g","caption":"Charles Ledoux"},"description":"Je suis un analyste sp\u00e9cialis\u00e9 dans les blockchains L1 et leurs fondamentaux comme Bitcoin, Kaspa, Monero, Chainlink ou encore Solana. Je suis \u00e9galement form\u00e9 au trading et \u00e0 l\u2019analyse technique depuis plus d\u2019un an sur le march\u00e9 des cryptomonnaies, mais \u00e9galement sur le forex et les m\u00e9taux pr\u00e9cieux comme l\u2019or ou le silver. J\u2019ai obtenu un dipl\u00f4me de la Crypto Academy sur les fondamentaux techniques du Bitcoin et poss\u00e8de une exp\u00e9rience de plus de 5 ans dans le journalisme et l\u2019\u00e9criture d\u2019articles p\u00e9dagogiques. J\u2019ai notamment \u00e9crit de nombreuses masterclass pour \u00e9duquer les nouveaux venus dans l'industrie et plus de 10 000 articles et news.J\u2019ai \u00e9galement pu interviewer de nombreux fondateurs et cr\u00e9ateurs de projets dans la crypto comme Marc Lebreton (chef marketing de la blockchain SUI), EJ Ayala (Coinbase US et Draftkings), et d\u2019autres projets comme Polyhedra (Eric Vreeland), Usual (Adli Takkal Bataille), ou encore Humanity Protocol (Jade Gu). J\u2019ai plong\u00e9 dans la cryptomonnaie il y a plus de 3 ans et continue de mettre tout en \u0153uvre pour fournir du contenu de qualit\u00e9, avec de l\u2019expertise et la neutralit\u00e9 attendue d\u2019un journaliste. Retrouvez moi aussi sur X pour des analyses et sur Linkedin pour me contacter.","sameAs":["https:\/\/www.linkedin.com\/in\/charles-ledoux-508392239\/","https:\/\/x.com\/charl3li"],"url":"https:\/\/investx.fr\/de\/author\/charles-ledoux\/"}]}},"_links":{"self":[{"href":"https:\/\/investx.fr\/de\/wp-json\/wp\/v2\/posts\/39978","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/investx.fr\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/investx.fr\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/investx.fr\/de\/wp-json\/wp\/v2\/users\/32"}],"replies":[{"embeddable":true,"href":"https:\/\/investx.fr\/de\/wp-json\/wp\/v2\/comments?post=39978"}],"version-history":[{"count":1,"href":"https:\/\/investx.fr\/de\/wp-json\/wp\/v2\/posts\/39978\/revisions"}],"predecessor-version":[{"id":39981,"href":"https:\/\/investx.fr\/de\/wp-json\/wp\/v2\/posts\/39978\/revisions\/39981"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/investx.fr\/de\/wp-json\/wp\/v2\/media\/39977"}],"wp:attachment":[{"href":"https:\/\/investx.fr\/de\/wp-json\/wp\/v2\/media?parent=39978"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/investx.fr\/de\/wp-json\/wp\/v2\/categories?post=39978"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/investx.fr\/de\/wp-json\/wp\/v2\/tags?post=39978"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}